{"id":1,"count":623,"description":"","link":"https:\/\/www.selfaligningbearing.com\/ru\/blog\/category\/selfaligningbearing\/","name":"selfaligningbearing","slug":"selfaligningbearing","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.selfaligningbearing.com\/ru\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.selfaligningbearing.com\/ru\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.selfaligningbearing.com\/ru\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.selfaligningbearing.com\/ru\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}